{"id":12594,"date":"2025-01-24T10:58:37","date_gmt":"2025-01-24T09:58:37","guid":{"rendered":"https:\/\/dragonflip.com\/?post_type=glossary&#038;p=12594"},"modified":"2025-01-24T10:58:38","modified_gmt":"2025-01-24T09:58:38","slug":"add-on","status":"publish","type":"glossary","link":"https:\/\/dragonflip.com\/de\/glossar\/add-on\/","title":{"rendered":"Add-On"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Eine <strong>Add-On-Akquisition<\/strong> ist eine &#xDC;bernahmestrategie, bei der ein <a class=\"glossaryLink\" title=\"Glossar: Finanzinvestor\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;Ein Finanzinvestor ist ein Investor (z. B. Private Equity oder Venture Capital), dessen prim&#xE4;res Ziel die Rendite aus seiner Investition ist, im Gegensatz zu strategischen K&#xE4;ufern, die(...)&lt;\/div&gt;\" href=\"https:\/\/dragonflip.com\/de\/glossar\/finanzinvestor\/\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Finanzinvestor<\/a> ein kleineres Unternehmen erwirbt und es in ein bereits bestehendes Portfoliounternehmen integriert. Ziel dieser Strategie ist es, die Marktstellung des Portfoliounternehmens auszubauen, Kosten zu senken und neue <a class=\"glossaryLink\"  title=\"Glossar: Synergien\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;&amp;lt;div class=&amp;quot;cmtt_meaning_label&amp;quot;&amp;gt;1&amp;lt;\/div&amp;gt;&amp;lt;strong&amp;gt;Synergien&amp;lt;\/strong&amp;gt; entstehen, wenn zwei Unternehmen durch eine Fusion oder &Uuml;bernahme mehr Wert schaffen k&ouml;nnen als die Summe ihrer Einzelwerte. Dies ist h&auml;ufig ein Hauptgrund f&uuml;r strategische K&auml;ufer,(...)&lt;\/div&gt;\"  href=\"https:\/\/dragonflip.com\/de\/glossar\/synergien\/\"  data-mobile-support=\"0\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>Synergien<\/a> zu schaffen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Vorteile einer Add-On-Akquisition:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Marktanteilsgewinn:<\/strong> Durch die &#xDC;bernahme eines Wettbewerbers oder komplement&#xE4;ren Unternehmens kann der Marktanteil erh&#xF6;ht werden.<\/li>\n\n\n\n<li><strong>Synergien:<\/strong> Gemeinsame Nutzung von Ressourcen wie Vertrieb, Einkauf oder Produktion senkt die Kosten.<\/li>\n\n\n\n<li><strong>Schnelles Wachstum:<\/strong> Die Add-On-Akquisition erm&#xF6;glicht organisches Wachstum durch den Erwerb etablierter Kundenst&#xE4;mme oder neuer Technologien.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>F&#xFC;r wen ist diese Strategie geeignet?<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Strategie wird vor allem von <strong>Private-Equity-Gesellschaften<\/strong> genutzt, um den Wert eines bestehenden Investments zu steigern. F&#xFC;r Verk&#xE4;ufer bietet die Add-On-Akquisition eine attraktive M&#xF6;glichkeit, ihre <strong>Firma zu verkaufen<\/strong>, insbesondere wenn Synergien f&#xFC;r den K&#xE4;ufer erkennbar sind.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine Add-On-Akquisition ist eine &#xDC;bernahmestrategie, bei der ein Finanzinvestor ein kleineres Unternehmen erwirbt und es in ein bereits bestehendes Portfoliounternehmen integriert. Ziel dieser Strategie ist es, die Marktstellung des Portfoliounternehmens auszubauen, Kosten zu senken und neue Synergien zu schaffen. Vorteile einer Add-On-Akquisition: F&#xFC;r wen ist diese Strategie geeignet? Diese Strategie wird vor allem von Private-Equity-Gesellschaften [&#x2026;]<\/p>\n","protected":false},"author":13,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"glossary-categories":[],"glossary-tags":[],"class_list":["post-12594","glossary","type-glossary","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Add-On - Dragonflip | Buy and Sell an Online Business<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/glossar\/add-on\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Add-On - Dragonflip | Buy and Sell an Online Business\" \/>\n<meta property=\"og:description\" content=\"Eine Add-On-Akquisition ist eine &#xDC;bernahmestrategie, bei der ein Finanzinvestor ein kleineres Unternehmen erwirbt und es in ein bereits bestehendes Portfoliounternehmen integriert. Ziel dieser Strategie ist es, die Marktstellung des Portfoliounternehmens auszubauen, Kosten zu senken und neue Synergien zu schaffen. Vorteile einer Add-On-Akquisition: F&#xFC;r wen ist diese Strategie geeignet? Diese Strategie wird vor allem von Private-Equity-Gesellschaften [&#x2026;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/glossar\/add-on\/\" \/>\n<meta property=\"og:site_name\" content=\"Dragonflip | Buy and Sell an Online Business\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-24T09:58:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/glossar\\\/add-on\\\/\",\"url\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/glossar\\\/add-on\\\/\",\"name\":\"Add-On - Dragonflip | Buy and Sell an Online Business\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#website\"},\"datePublished\":\"2025-01-24T09:58:37+00:00\",\"dateModified\":\"2025-01-24T09:58:38+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/glossar\\\/add-on\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/glossar\\\/add-on\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/glossar\\\/add-on\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dragonflip.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Add-On\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#website\",\"url\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/\",\"name\":\"Dragonflip | Buy and Sell an Online Business\",\"description\":\"Buy and Sell an Online Business\",\"publisher\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#organization\",\"name\":\"Dragonflip GmbH\",\"url\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dragonflip.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/2019-07-31-logo-dragonflip-website-white.svg\",\"contentUrl\":\"https:\\\/\\\/dragonflip.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/2019-07-31-logo-dragonflip-website-white.svg\",\"width\":1,\"height\":1,\"caption\":\"Dragonflip GmbH\"},\"image\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Add-On - Dragonflip | Buy and Sell an Online Business","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/glossar\/add-on\/","og_locale":"de_DE","og_type":"article","og_title":"Add-On - Dragonflip | Buy and Sell an Online Business","og_description":"Eine Add-On-Akquisition ist eine &#xDC;bernahmestrategie, bei der ein Finanzinvestor ein kleineres Unternehmen erwirbt und es in ein bereits bestehendes Portfoliounternehmen integriert. Ziel dieser Strategie ist es, die Marktstellung des Portfoliounternehmens auszubauen, Kosten zu senken und neue Synergien zu schaffen. Vorteile einer Add-On-Akquisition: F&#xFC;r wen ist diese Strategie geeignet? Diese Strategie wird vor allem von Private-Equity-Gesellschaften [&#x2026;]","og_url":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/glossar\/add-on\/","og_site_name":"Dragonflip | Buy and Sell an Online Business","article_modified_time":"2025-01-24T09:58:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/glossar\/add-on\/","url":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/glossar\/add-on\/","name":"Add-On - Dragonflip | Buy and Sell an Online Business","isPartOf":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#website"},"datePublished":"2025-01-24T09:58:37+00:00","dateModified":"2025-01-24T09:58:38+00:00","breadcrumb":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/glossar\/add-on\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/glossar\/add-on\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/glossar\/add-on\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dragonflip.com\/en\/"},{"@type":"ListItem","position":2,"name":"Add-On"}]},{"@type":"WebSite","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#website","url":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/","name":"Dragonflip | Buy and Sell an Online Business","description":"Buy and Sell an Online Business","publisher":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#organization","name":"Dragonflip GmbH","url":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dragonflip.com\/wp-content\/uploads\/2019\/07\/2019-07-31-logo-dragonflip-website-white.svg","contentUrl":"https:\/\/dragonflip.com\/wp-content\/uploads\/2019\/07\/2019-07-31-logo-dragonflip-website-white.svg","width":1,"height":1,"caption":"Dragonflip GmbH"},"image":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/glossary\/12594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/users\/13"}],"version-history":[{"count":1,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/glossary\/12594\/revisions"}],"predecessor-version":[{"id":12595,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/glossary\/12594\/revisions\/12595"}],"wp:attachment":[{"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/media?parent=12594"}],"wp:term":[{"taxonomy":"glossary-categories","embeddable":true,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/glossary-categories?post=12594"},{"taxonomy":"glossary-tags","embeddable":true,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/glossary-tags?post=12594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}