{"id":1059,"date":"2019-09-24T14:59:38","date_gmt":"2019-09-24T13:59:38","guid":{"rendered":"https:\/\/dragonflip.com\/?p=1059"},"modified":"2026-02-05T14:28:40","modified_gmt":"2026-02-05T13:28:40","slug":"verkauf-eines-e-commerce-business-aus-steuerlicher-sicht","status":"publish","type":"post","link":"https:\/\/dragonflip.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/","title":{"rendered":"Verkauf eines E-Commerce Business \u2013 Warum eine steuerliche Pru\u0308fung sinnvoll ist"},"content":{"rendered":"<div>\n<p>Der Kauf oder Verkauf eines Betriebs stellt f&#xFC;r den Unternehmer immer ein besonderes Ereignis dar. Gerade der Kauf und die Ver&#xE4;u&#xDF;erung einer Firma bergen sowohl Chancen als auch Risiken, welche bei langfristiger Planung und gewissenhafter Beratung zum eigenen Vorteil genutzt werden k&#xF6;nnen. In der nachfolgenden Diskussion der unterschiedlichen Varianten der Unternehmens&#xFC;bertragung soll der Blick insbesondere auf Amazon-H&#xE4;ndler gelegt werden, f&#xFC;r die der Hauptwert des Unternehmens in der eigenen Marke besteht.<\/p>\n<p>Zun&#xE4;chst sollen die verschiedenen Ausgangssituationen und deren steuerliche Behandlung erl&#xE4;utert werden. Bei der Ver&#xE4;u&#xDF;erung von Unternehmen wird grunds&#xE4;tzlich in drei Fallgruppen unterschieden: Verkauf eines Einzelunternehmens, Verkauf bei einer Kapitalgesellschaft und Verkauf der Tochtergesellschaft einer Holding. Im Anschluss wird gekl&#xE4;rt, wie der Wechsel zu einer g&#xFC;nstigeren Besteuerungsform m&#xF6;glich ist, es wird die K&#xE4;ufersicht kurz angerissen und ein Ausblick auf das internationale Steuerrecht gegeben.<\/p>\n<\/div>\n\n\n\n<h1 class=\"wp-block-heading\"><strong>Verkauf eines Einzelunternehmens<\/strong><\/h1>\n\n\n\n<div>\n<p>Im ersten Fall handelt es sich bei dem Unternehmen, welches verkauft werden soll, um ein <a class=\"glossaryLink\" title=\"Glossar: Einzelunternehmen\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;Das Einzelunternehmen ist die einfachste Unternehmensform, bei der eine Person alleiniger Inhaber und Tr&#xE4;ger der unternehmerischen Verantwortung ist.&amp;lt;br\/&amp;gt;&amp;lt;strong&amp;gt;Merkmale:&amp;lt;\/strong&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;strong&amp;gt;Haftung:&amp;lt;\/strong&amp;gt; Der Inhaber haftet(...)&lt;\/div&gt;\" href=\"https:\/\/dragonflip.com\/de\/glossar\/einzelunternehmen\/\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Einzelunternehmen<\/a>. Dies hat zur Folge, dass ein Gewerbebetrieb ver&#xE4;u&#xDF;ert wird und die daraus resultierenden Gewinne beim Ver&#xE4;u&#xDF;erer in die Eink&#xFC;nfte aus Gewerbebetrieb nach &#xA7; 16 EStG einzuordnen sind.<\/p>\n<h5><strong>Hohe Steuerbelastung bei der Ver&#xE4;u&#xDF;erung eines Einzelunternehmens<\/strong><\/h5>\n<p>Diese Eink&#xFC;nfte sind grunds&#xE4;tzlich voll steuerpflichtig, allerdings kann unter Umst&#xE4;nden ein Freibetrag abgezogen werden, beispielsweise ab einem Alter von 55 Jahren. Diese Eink&#xFC;nfte unterliegen dem pers&#xF6;nlichen Einkommenssteuersatz, welcher bei bis zu 45 % liegen kann. Der zu versteuernde Gewinn ermittelt sich aus der Differenz des Verkaufspreises und des bilanziellen Eigenkapitals des Unternehmens abz&#xFC;glich etwaiger Ver&#xE4;u&#xDF;erungsnebenkosten, falls der Verk&#xE4;ufer diese tr&#xE4;gt.<\/p>\n<h5><strong>Wechsel zur Bilanz kann erforderlich sein<\/strong><\/h5>\n<p>Bei der Berechnung der Eink&#xFC;nfte ist zu beachten, dass eine &#xDC;berleitungsrechnung aufzustellen ist, wenn der Gewinn bisher durch Einnahmen-&#xDC;berschuss-Rechnung ermittelt wurde. Im Rahmen der &#xDC;berleitungsrechnung werden u. a. s&#xE4;mtliche Warenbest&#xE4;nde, Forderungen, Verbindlichkeiten und R&#xFC;ckstellungen aktiviert bzw. passiviert. Ein etwaiger &#xDC;berleitungsgewinn- oder Verlust unterliegt der laufenden Besteuerung (d. h. auch Gewerbesteuer). Insbesondere durch vorher nicht aktivierte Warenbest&#xE4;nde k&#xF6;nnen hierbei schnell hohe Summen zusammenkommen, sodass dies bei der Preisfindung einkalkuliert werden sollte.<\/p>\n<h5><strong>Steueroptimierungen sind m&#xF6;glich und sollten gepr&#xFC;ft werden<\/strong><\/h5>\n<p>Eine M&#xF6;glichkeit, wie es eventuell zu einer tempor&#xE4;ren Steuerminderung kommen kann, w&#xE4;re die Zuflussbesteuerung, bei der der Verkaufspreis &#xFC;ber mehrere Jahre gezahlt wird.<\/p>\n<p>Eine weitere Option liegt in der Kirchensteuer. Dabei kann es sich lohnen, im Jahr der gepalten Ver&#xE4;u&#xDF;erung hohe Kirchensteuervorauszahlungen an das Finanzamt zu zahlen, da in diesem Zuge die Kirchensteuer als Sonderbetriebsausgabe geltend gemacht werden kann. Allerdings muss insgesamt gesagt werden, dass der Verkauf eines Einzelunternehmens die wohl unvorteilhafteste Variante darstellt, da sie mit einer enorm hohen Steuerbelastung ein- hergeht. Von Vorteil ist dies wohl nur dann, wenn entweder der Steuersatz niedrig ist oder mit dem Verkauf ein Verlust realisiert wird.<\/p>\n<h5><strong>Vorteile f&#xFC;r den K&#xE4;ufer des Unternehmens<\/strong><\/h5>\n<p>F&#xFC;r den K&#xE4;ufer eines Online-Handelsunternehmens k&#xF6;nnen sich im Gegenzug auch erhebliche steuerliche Vorteile ergeben, wenn der Online-Shop von einem Einzelunternehmer gekauft wird. Der steuerliche Vorteil liegt darin, dass der Kaufpreis vom neuen Betriebsinhaber zuk&#xFC;nftig abgeschrieben und in bestimmten F&#xE4;llen auch sofort steuerlich geltend gemacht werden kann. Hierdurch ergibt sich auf Ebene des Betriebserwerbers ein unmittelbarer steuerlicher Vorteil im Jahr des Betriebs&#xFC;bergangs.<\/p>\n<p>Auch wenn der Kaufpreis abgeschrieben werden muss, wird der Kaufpreis in der Regel &#xFC;ber einen Zeitraum von 3 bis 15 Jahren steuermindernd ber&#xFC;cksichtigt. Hierdurch spart der K&#xE4;ufer &#x2013; abh&#xE4;ngig von seinem individuellen Steuersatz &#x2013; bis zu 45% Einkommens- und Gewerbe- steuer.<\/p>\n<p>Die genaue H&#xF6;he der zuk&#xFC;nftigen Steuerersparnis sollte genau ermittelt werden, denn nur so kann abgesch&#xE4;tzt werden ob die H&#xF6;he des Kaufpreises gerechtfertigt ist.<\/p>\n<\/div>\n\n\n\n<h1 class=\"wp-block-heading\"><strong>Verkauf einer Kapitalgesellschaft<\/strong><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Verkauf der Marke einer Kapitalgesellschaft <\/strong><\/h2>\n\n\n\n<div>\n<p>Eine Konstellation, welche sich in Verbindung mit einer Kapitalgesellschaft (z. B. <a class=\"glossaryLink\"  title=\"Glossar: GmbH\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;Die GmbH (Gesellschaft mit beschr&auml;nkter Haftung) ist eine der h&auml;ufigsten Rechtsformen in Deutschland und zeichnet sich durch eine Haftungsbeschr&auml;nkung der Gesellschafter auf die H&ouml;he ihrer(...)&lt;\/div&gt;\"  href=\"https:\/\/dragonflip.com\/de\/glossar\/gmbh\/\"  data-mobile-support=\"0\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>GmbH<\/a>) ergibt, ist der Verkauf der Marke an sich (<a class=\"glossaryLink\" title=\"Glossar: Asset Deal\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;&amp;lt;div class=&amp;quot;cmtt_meaning_label&amp;quot;&amp;gt;1&amp;lt;\/div&amp;gt;Ein &amp;lt;strong&amp;gt;Asset Deal&amp;lt;\/strong&amp;gt; bezeichnet - im Gegensatz zum Share Deal - den Verkauf von Verm&#xF6;genswerten eines Unternehmens, z.B. Immobilien, Maschinen oder Patente. Bei einem &amp;lt;strong&amp;gt;Asset Deal&amp;lt;\/strong&amp;gt; erwirbt der K&#xE4;ufer(...)&lt;\/div&gt;\" href=\"https:\/\/dragonflip.com\/de\/glossar\/asset-deal\/\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Asset Deal<\/a>). In diesem Fall wird nicht der gesamte Betrieb der Kapitalgesellschaft &#xFC;bertragen, sondern nur ein bestimmter Teil, wie eben zum Beispiel die Marke.<\/p>\n<p>Dabei entsteht der Gewinn auf Ebene der Kapitalgesellschaft. Dieser Gewinn f&#xE4;llt sowohl unter die K&#xF6;rperschaftsteuer als auch unter die Gewerbesteuer, welche summiert eine Steuerlast von zirka 30 % auf den Ver&#xE4;u&#xDF;erungsgewinn ergibt. Das Kapital, welches aus der Ver&#xE4;u&#xDF;erung der Marke entsteht, kann genutzt werden, um innerhalb der Kapitalgesellschaft damit zu arbeiten, Investitionen zu t&#xE4;tigen oder neue Gesch&#xE4;fte aufzubauen. Ebenso kann der Gewinn an die Privatperson ausgesch&#xFC;ttet werden, was allerdings zur Folge hat, dass die Aussch&#xFC;ttung mit mindestens 25 % Kapitalertragsteuer zuz&#xFC;glich Solidarit&#xE4;tszuschlag besteuert wird.<\/p>\n<p>Im Ergebnis f&#xFC;hrt dies bei einer Thesaurierung des Ver&#xE4;u&#xDF;erungsgewinns auf Gesellschafts- ebene zu einer geringeren Steuerbelastung des Gewinns von bis zu 15 %. Erst bei Aussch&#xFC;ttung des Gewinns ist das steuerliche Ergebnis &#xE4;hnlich wie beim Verkauf des Einzelunternehmens.<\/p>\n<h5><strong>Steuerliche Vorteile f&#xFC;r den Verk&#xE4;ufer der Marke<\/strong><\/h5>\n<p>F&#xFC;r den Ver&#xE4;u&#xDF;erer in der Form der Kapitalgesellschaft ergibt sich in diesem Fall ein Steuervorteil gegen&#xFC;ber der Ver&#xE4;u&#xDF;erung eines Einzelunternehmens. Denn die Steuerbelastung betr&#xE4;gt &#x201E;nur&#x201C; rund 30 %; wohingegen sich eine Steuerbelastung als Einzelunternehmen von bis zu 45 % ergeben kann. Diese Variante ist aber nur dann zu empfehlen, wenn der Ver&#xE4;u&#xDF;erungsgewinn nicht direkt an den Unternehmer ausgesch&#xFC;ttet, sondern mit dem Ver&#xE4;u&#xDF;erungsgewinn auf Ebene der Kapitalgesellschaft weitergearbeitet werden soll.<\/p>\n<h5><strong>Keine Nachteile f&#xFC;r den Erwerber der Marke<\/strong><\/h5>\n<p>In diesem Fall ergeben sich keine besonderen, steuerlichen Nachteile f&#xFC;r den Erwerber, denn der Kaufpreis f&#xFC;r die Marke oder sonstigen Bestandteile des Online-Shops kann ebenso wie beim Erwerb von einem Einzelunternehmer steuerlich geltend gemacht werden.<\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Verkauf einer Kapitalgesellschaft an sich<\/strong><\/h2>\n\n\n\n<div>\n<p>Ein weiteres Szenario, welches steuerrechtlich differenziert betrachtet werden muss, ist der Verkauf einer Kapitalgesellschaft im Ganzen (<a class=\"glossaryLink\" title=\"Glossar: Share Deal\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;&amp;lt;div class=&amp;quot;cmtt_meaning_label&amp;quot;&amp;gt;1&amp;lt;\/div&amp;gt;Ein &amp;lt;strong&amp;gt;Share Deal&amp;lt;\/strong&amp;gt; bezeichnet - im Gegensatz zum Asset Deal, welcher sich auf den Verkauf einzelner Verm&#xF6;gensgegenst&#xE4;nde bezieht - den Verkauf von Anteilen (Aktien oder Gesellschaftsanteilen) eines(...)&lt;\/div&gt;\" href=\"https:\/\/dragonflip.com\/de\/glossar\/share-deal\/\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Share Deal<\/a>).<\/p>\n<p>Dies hat zur Folge, dass die Privatperson einen Gewinn aus der Ver&#xE4;u&#xDF;erung von Anteilen an der Kapitalgesellschaft hat und grunds&#xE4;tzlich ebenfalls in die Eink&#xFC;nfte aus Gewerbebetrieb nach &#xA7; 17 EStG einzuordnen sind.<\/p>\n<h5><strong>Gewinn aus der Ver&#xE4;u&#xDF;erung der Anteile an der Kapitalgesellschaft wird nur teilweise versteuert<\/strong><\/h5>\n<p>Diese Eink&#xFC;nfte unterliegen zwar auch der Einkommensteuer in H&#xF6;he des pers&#xF6;nlichen Steuersatzes, allerdings kann in dieser Fallgruppe das Teileink&#xFC;nfteverfahren angewandt werden, was zur Folge hat, dass der<strong> Ver&#xE4;u&#xDF;erungsgewinn<\/strong> <strong>zu 40 % steuerfrei<\/strong> ist und die Anschaffungskosten der Anteile zu 40 % nicht abziehbar sind. Im Saldo ergibt dies, dass nur 60 % der Gewinne aus der Ver&#xE4;u&#xDF;erung zu versteuern sind. Im Ergebnis ergibt sich bei dieser Variante also eine <strong>geringere Steuerbelastung von bis zu 18 % auf den Gewinn<\/strong>.<\/p>\n<h5><strong>Steuerliche Nachteile f&#xFC;r den Erwerber der Anteile<\/strong><\/h5>\n<p>Auch wenn diese Variante f&#xFC;r den Ver&#xE4;u&#xDF;erer erhebliche, steuerliche Vorteile bietet, ergeben sich f&#xFC;r den Ver&#xE4;u&#xDF;erer steuerliche Nachteile. Denn der zu bezahlende Kaufpreis kann nicht sofort steuerlich geltend gemacht werden, sondern im Regelfall nur bei Weiterver&#xE4;u&#xDF;erung oder Liquidation der erworbenen Kapitalgesellschaft. Der Erwerber einer Kapitalgesellschaft sollte den erheblichen Nachteil gegen&#xFC;ber des Erwerbs eines Einzelunternehmens unbedingt bedenken und bei seiner Kalkulation ber&#xFC;cksichtigen.<\/p>\n<p>Besonders problematisch kann sich dieser Fall auswirken, wenn der Kaufpreis &#xFC;ber ein Kreditinstitut finanziert wird. Denn auch die an die Bank zu leistende Kredittilgung kann nicht steuerlich geltend gemacht werden. Eine genaue Berechnung der Steuerbelastung nach dem Erwerb der Anteile ist deshalb unbedingt angebracht.<\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Verkauf der Tochtergesellschaft einer Holding<\/strong><\/h2>\n\n\n\n<div>\n<h5><strong>Nahezu steuerfreie Ver&#xE4;u&#xDF;erung m&#xF6;glich<\/strong><\/h5>\n<p>Die wohl, aus Sicht des Verk&#xE4;ufers, vorteilhafteste Variante ist der Verkauf der Tochtergesellschaft einer Holding. Verkauft eine Kapitalgesellschaft Anteile einer anderen Kapitalgesellschaft, ist der resultierende Gewinn zu 95 % steuerfrei. Dies bedeutet, dass etwa 5 % des Gewinnes dem Steuersatz der Kapitalgesellschaft von 30 % (K&#xF6;rperschaftsteuer und Gewerbesteuer) unterliegen und dies am Ende eine Steuerlast auf den <strong>Ver&#xE4;u&#xDF;erungsgewinn von 1,5 % ergibt.<\/strong><\/p>\n<p>Bei Aussch&#xFC;ttungen werden hier wieder 25% Kapitalertragsteuer zzgl. Solidarit&#xE4;tszuschlag f&#xE4;llig. Jedoch ist dies auch bei einer Aussch&#xFC;ttung wesentlich g&#xFC;nstiger als der Verkauf eines Einzelunternehmens.<\/p>\n<p>Vergleicht man die verschiedenen Fallgruppen miteinander, kann eindeutig gesagt werden, dass der Verkauf im Zusammenhang mit einer Holding die beste Variante darstellt.<\/p>\n<h5><strong>Auch hier: Steuerliche Nachteile f&#xFC;r den Erwerber der Anteile<\/strong><\/h5>\n<p>Der Erwerber von Anteilen an einer Kapitalgesellschaft hat den steuerlichen Nachteil, dass er den Kaufpreis f&#xFC;r die Anteile nicht planm&#xE4;&#xDF;ig abschreiben kann und somit keinen direkten Steuervorteil hat.<\/p>\n<h5><strong>Beim Unternehmenskauf oder Unternehmensverkauf ist eine steuerliche Pr&#xFC;fung sinnvoll<\/strong><\/h5>\n<p>Wie sich zeigt, ist es &#xE4;u&#xDF;erst sinnvoll, eine steuerliche Pr&#xFC;fung bei einem geplanten Unternehmens&#xFC;bergang vornehmen zu lassen.<\/p>\n<p>Einerseits k&#xF6;nnen sich beim Verkauf eines Einzelunternehmens f&#xFC;r den Verk&#xE4;ufer gewisse Steuervorteile durch die Ausnutzung von Freibetr&#xE4;gen oder Steuerstundungseffekten realisieren lassen. Ebenso lohnt es sich, bei einem in der Zukunft geplanten Unternehmensverkauf &#xFC;ber die Umwandlung eines Einzelunternehmens in eine Kapitalgesellschaft &#x2013; oder umgekehrt &#x2013; nachzudenken, um eine m&#xF6;glichst geringe Steuerbelastung auf den Gewinn aus der Ver&#xE4;u&#xDF;erung des Online-Handels zu erreichen,<\/p>\n<p>Auch f&#xFC;r den Erwerber eines Online-Handelsunternehmens ist es &#xE4;u&#xDF;erst sinnvoll, eine steuerliche Pr&#xFC;fung vornehmen und die zuk&#xFC;nftige Steuerbelastung errechnen zu lassen. Dies gilt insbesondere, wenn der Kaufpreis f&#xFC;r den Erwerb des E-Commerce-Business durch eine Bank finanziert wurde.<\/p>\n<p>Zumeist wird ein hoher Kaufpreis gezahlt, um das Unternehmen zu erwerben, welches erst &#xFC;ber einen l&#xE4;ngeren Zeitraum Gewinne abwirft, die den Kaufpreis rechtfertigen. Hier sollte sichergestellt werden, dass der Kaufpreis auch steuerlich geltend gemacht werden kann. Ist dies nicht m&#xF6;glich, weil beispielsweise Anteile an einer Kapitalgesellschaft erworben werden, sollte dies bei der Kaufpreisfindung ber&#xFC;cksichtigt werden.<\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">L<strong>assen Sie den Kauf oder Verkauf Ihres Online-Shops von einem Profi pr&#xFC;fen <\/strong><\/h2>\n\n\n\n<div>\n<p>Wir von <a href=\"http:\/\/steuerberaten.de\" target=\"_blank\" rel=\"noopener\">steuerberaten.de<\/a> sind Marktf&#xFC;hrer in der Online-Steuerberatung. Seit 2009 betreuen wir hunderte Online-H&#xE4;ndler in unserem digitalen Steuerb&#xFC;ro. Aufgrund unserer besonders hohen Branchenkenntnis sind wir sehr gut in der Lage, Sie beim Kauf oder Verkauf Ihres Online-Shops zu begleiten. Wir k&#xF6;nnen beispielsweise als Ihr betriebswirtschaftlicher Sparringspartner f&#xFC;r den Kauf und Verkauf fungieren sowie Ihre steuerliche Situation analysieren und optimieren, damit Sie beim Kauf oder Verkauf des Online-Shops eine m&#xF6;glichst hohe Steuerersparnis erzielen.<\/p>\n<\/div>\n\n\n\n<div>\n<p><strong>&#xDC;ber den Autor<\/strong><\/p>\n<\/div>\n\n\n\n<div>\n<p>Martin Mei&#xDF;ner startete seine Laufbahn innerhalb der Finanzverwaltung, um von dort zu einer der gr&#xF6;&#xDF;ten Wirtschaftspr&#xFC;fungs- und Steuerberatungsgesellschaften zu wechseln. Dort lag der Schwerpunkt bei der Beratung von gro&#xDF;en mittelst&#xE4;ndischen Unternehmen und internationalen Konzernen. Seit einiger Zeit verst&#xE4;rkt Martin Mei&#xDF;ner das Team von <a href=\"http:\/\/steuerberaten.de\/\">steuerberaten.de<\/a>, einer der innovativsten Steuerberatungsgesellschaften des Landes. Wir beraten Onlineh&#xE4;ndler bei allen Fragen des nationalen und internationalen Steuerrechts und helfen ihnen dabei, ihren steuerlichen Pflichten so effizient wie m&#xF6;glich nachzukommen.<\/p>\n<\/div>\n\n\n\n<li><a href=\"https:\/\/dragonflip.com\/de\/exit-vorbereitung\/%20\">Wie Sie sich auf ein <\/a><a class=\"glossaryLink\" title=\"Glossar: Indikatives Angebot\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemBody&gt;&amp;lt;script type=&amp;quot;application\/ld+json&amp;quot;&amp;gt;{  &amp;quot;@context&amp;quot;: &amp;quot;https:\/\/schema.org&amp;quot;,  &amp;quot;@type&amp;quot;: &amp;quot;DefinedTerm&amp;quot;,  &amp;quot;name&amp;quot;: &amp;quot;Indikatives Angebot&amp;quot;,  &amp;quot;description&amp;quot;: &amp;quot;Ein indikatives Angebot (Indicative Offer) ist ein unverbindliches erstes(...)&amp;lt;\/script&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/dragonflip.com\/de\/glossar\/indikatives-angebot\/\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">indikatives Angebot<\/a> richtig vorbereiten<\/li>\n<li><a href=\"https:\/\/dragonflip.com\/de\/steuern-beim-unternehmensverkauf\/\">Umfassender Steuer-Guide f&#xFC;r den Unternehmensverkauf<\/a><\/li>\n<li><a href=\"https:\/\/dragonflip.com\/de\/onlineshop-verkaufen\/\">Der komplette Guide zum Onlineshop-Verkauf<\/a><\/li>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Kauf oder Verkauf eines Betriebs stellt f&#xFC;r den Unternehmer immer ein besonderes Ereignis dar. Gerade der Kauf und die Ver&#xE4;u&#xDF;erung einer Firma bergen sowohl Chancen als auch Risiken, welche bei langfristiger Planung und gewissenhafter Beratung zum eigenen Vorteil genutzt werden k&#xF6;nnen. In der nachfolgenden Diskussion der unterschiedlichen Varianten der Unternehmens&#xFC;bertragung soll der Blick insbesondere [&#x2026;]<\/p>\n","protected":false},"author":3,"featured_media":9271,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23,1],"tags":[],"class_list":["post-1059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-german","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verkauf eines E-Commerce Business \u2013 Warum eine steuerliche Pru\u0308fung sinnvoll ist - Dragonflip | Buy and Sell an Online Business<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verkauf eines E-Commerce Business \u2013 Warum eine steuerliche Pru\u0308fung sinnvoll ist - Dragonflip | Buy and Sell an Online Business\" \/>\n<meta property=\"og:description\" content=\"Der Kauf oder Verkauf eines Betriebs stellt f&#xFC;r den Unternehmer immer ein besonderes Ereignis dar. Gerade der Kauf und die Ver&#xE4;u&#xDF;erung einer Firma bergen sowohl Chancen als auch Risiken, welche bei langfristiger Planung und gewissenhafter Beratung zum eigenen Vorteil genutzt werden k&#xF6;nnen. In der nachfolgenden Diskussion der unterschiedlichen Varianten der Unternehmens&#xFC;bertragung soll der Blick insbesondere [&#x2026;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/\" \/>\n<meta property=\"og:site_name\" content=\"Dragonflip | Buy and Sell an Online Business\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-24T13:59:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T13:28:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/wp-content\/uploads\/2023\/11\/Steuern-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Timo Bock\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Timo Bock\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"15\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/\"},\"author\":{\"name\":\"Timo Bock\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#\\\/schema\\\/person\\\/38f7a9fd5b8cd10c7adf2464e311ec3d\"},\"headline\":\"Verkauf eines E-Commerce Business \u2013 Warum eine steuerliche Pru\u0308fung sinnvoll ist\",\"datePublished\":\"2019-09-24T13:59:38+00:00\",\"dateModified\":\"2026-02-05T13:28:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/\"},\"wordCount\":1767,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dragonflip.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Steuern-scaled.jpg\",\"articleSection\":[\"German\",\"Unkategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/\",\"url\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/\",\"name\":\"Verkauf eines E-Commerce Business \u2013 Warum eine steuerliche Pru\u0308fung sinnvoll ist - Dragonflip | Buy and Sell an Online Business\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dragonflip.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Steuern-scaled.jpg\",\"datePublished\":\"2019-09-24T13:59:38+00:00\",\"dateModified\":\"2026-02-05T13:28:40+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dragonflip.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Steuern-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/dragonflip.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Steuern-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dragonflip.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verkauf eines E-Commerce Business \u2013 Warum eine steuerliche Pru\u0308fung sinnvoll ist\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#website\",\"url\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/\",\"name\":\"Dragonflip | Buy and Sell an Online Business\",\"description\":\"Buy and Sell an Online Business\",\"publisher\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#organization\",\"name\":\"Dragonflip GmbH\",\"url\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dragonflip.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/2019-07-31-logo-dragonflip-website-white.svg\",\"contentUrl\":\"https:\\\/\\\/dragonflip.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/2019-07-31-logo-dragonflip-website-white.svg\",\"width\":1,\"height\":1,\"caption\":\"Dragonflip GmbH\"},\"image\":{\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/dragonflip.com.w01d6fed.kasserver.com\\\/de\\\/#\\\/schema\\\/person\\\/38f7a9fd5b8cd10c7adf2464e311ec3d\",\"name\":\"Timo Bock\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dad9ad85459c71085d44a0d299811eaf352b063820012097bb4f42231181867f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dad9ad85459c71085d44a0d299811eaf352b063820012097bb4f42231181867f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dad9ad85459c71085d44a0d299811eaf352b063820012097bb4f42231181867f?s=96&d=mm&r=g\",\"caption\":\"Timo Bock\"},\"url\":\"https:\\\/\\\/dragonflip.com\\\/de\\\/author\\\/timo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verkauf eines E-Commerce Business \u2013 Warum eine steuerliche Pru\u0308fung sinnvoll ist - Dragonflip | Buy and Sell an Online Business","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/","og_locale":"de_DE","og_type":"article","og_title":"Verkauf eines E-Commerce Business \u2013 Warum eine steuerliche Pru\u0308fung sinnvoll ist - Dragonflip | Buy and Sell an Online Business","og_description":"Der Kauf oder Verkauf eines Betriebs stellt f&#xFC;r den Unternehmer immer ein besonderes Ereignis dar. Gerade der Kauf und die Ver&#xE4;u&#xDF;erung einer Firma bergen sowohl Chancen als auch Risiken, welche bei langfristiger Planung und gewissenhafter Beratung zum eigenen Vorteil genutzt werden k&#xF6;nnen. In der nachfolgenden Diskussion der unterschiedlichen Varianten der Unternehmens&#xFC;bertragung soll der Blick insbesondere [&#x2026;]","og_url":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/","og_site_name":"Dragonflip | Buy and Sell an Online Business","article_published_time":"2019-09-24T13:59:38+00:00","article_modified_time":"2026-02-05T13:28:40+00:00","og_image":[{"width":2560,"height":1707,"url":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/wp-content\/uploads\/2023\/11\/Steuern-scaled.jpg","type":"image\/jpeg"}],"author":"Timo Bock","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Timo Bock","Gesch\u00e4tzte Lesezeit":"15\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/#article","isPartOf":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/"},"author":{"name":"Timo Bock","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#\/schema\/person\/38f7a9fd5b8cd10c7adf2464e311ec3d"},"headline":"Verkauf eines E-Commerce Business \u2013 Warum eine steuerliche Pru\u0308fung sinnvoll ist","datePublished":"2019-09-24T13:59:38+00:00","dateModified":"2026-02-05T13:28:40+00:00","mainEntityOfPage":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/"},"wordCount":1767,"commentCount":0,"publisher":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#organization"},"image":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/#primaryimage"},"thumbnailUrl":"https:\/\/dragonflip.com\/wp-content\/uploads\/2023\/11\/Steuern-scaled.jpg","articleSection":["German","Unkategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/","url":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/","name":"Verkauf eines E-Commerce Business \u2013 Warum eine steuerliche Pru\u0308fung sinnvoll ist - Dragonflip | Buy and Sell an Online Business","isPartOf":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#website"},"primaryImageOfPage":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/#primaryimage"},"image":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/#primaryimage"},"thumbnailUrl":"https:\/\/dragonflip.com\/wp-content\/uploads\/2023\/11\/Steuern-scaled.jpg","datePublished":"2019-09-24T13:59:38+00:00","dateModified":"2026-02-05T13:28:40+00:00","breadcrumb":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/#primaryimage","url":"https:\/\/dragonflip.com\/wp-content\/uploads\/2023\/11\/Steuern-scaled.jpg","contentUrl":"https:\/\/dragonflip.com\/wp-content\/uploads\/2023\/11\/Steuern-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/verkauf-eines-e-commerce-business-aus-steuerlicher-sicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dragonflip.com\/en\/"},{"@type":"ListItem","position":2,"name":"Verkauf eines E-Commerce Business \u2013 Warum eine steuerliche Pru\u0308fung sinnvoll ist"}]},{"@type":"WebSite","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#website","url":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/","name":"Dragonflip | Buy and Sell an Online Business","description":"Buy and Sell an Online Business","publisher":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#organization","name":"Dragonflip GmbH","url":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dragonflip.com\/wp-content\/uploads\/2019\/07\/2019-07-31-logo-dragonflip-website-white.svg","contentUrl":"https:\/\/dragonflip.com\/wp-content\/uploads\/2019\/07\/2019-07-31-logo-dragonflip-website-white.svg","width":1,"height":1,"caption":"Dragonflip GmbH"},"image":{"@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/dragonflip.com.w01d6fed.kasserver.com\/de\/#\/schema\/person\/38f7a9fd5b8cd10c7adf2464e311ec3d","name":"Timo Bock","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/dad9ad85459c71085d44a0d299811eaf352b063820012097bb4f42231181867f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dad9ad85459c71085d44a0d299811eaf352b063820012097bb4f42231181867f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dad9ad85459c71085d44a0d299811eaf352b063820012097bb4f42231181867f?s=96&d=mm&r=g","caption":"Timo Bock"},"url":"https:\/\/dragonflip.com\/de\/author\/timo\/"}]}},"jetpack_featured_media_url":"https:\/\/dragonflip.com\/wp-content\/uploads\/2023\/11\/Steuern-scaled.jpg","_links":{"self":[{"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/posts\/1059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/comments?post=1059"}],"version-history":[{"count":16,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/posts\/1059\/revisions"}],"predecessor-version":[{"id":14077,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/posts\/1059\/revisions\/14077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/media\/9271"}],"wp:attachment":[{"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/media?parent=1059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/categories?post=1059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dragonflip.com\/de\/wp-json\/wp\/v2\/tags?post=1059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}